{"id":7831,"date":"2026-05-12T19:09:34","date_gmt":"2026-05-12T19:09:34","guid":{"rendered":"https:\/\/aims-senegal.org\/?p=7831"},"modified":"2026-05-12T19:09:34","modified_gmt":"2026-05-12T19:09:34","slug":"aims-senegal-alumni-meet-up-2026","status":"publish","type":"post","link":"https:\/\/aims-senegal.org\/fr\/aims-senegal-alumni-meet-up-2026\/","title":{"rendered":"AIMS Senegal Alumni Meet-up 2026"},"content":{"rendered":"<p>Le 22 mai prochain, nous allons mettre de c\u00f4t\u00e9 les algorithmes pour privil\u00e9gier l\u2019essentiel : l\u2019humain. Le cadre magnifique de la Corniche des Almadies devient le th\u00e9\u00e2tre de nos retrouvailles au Jet Caf\u00e9 Beach, pour une soir\u00e9e d\u2019exception o\u00f9 vos parcours se croisent \u00e0 nouveau. C\u2019est le moment de c\u00e9l\u00e9brer l\u2019h\u00e9ritage de l\u2019AIMS S\u00e9n\u00e9gal et de b\u00e2tir les synergies de demain.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 22 mai prochain, nous allons mettre de c\u00f4t\u00e9 les algorithmes pour privil\u00e9gier l\u2019essentiel : l\u2019humain. Le cadre magnifique de la Corniche des Almadies devient le th\u00e9\u00e2tre de nos retrouvailles au Jet Caf\u00e9 Beach, pour une soir\u00e9e d\u2019exception o\u00f9 vos parcours se croisent \u00e0 nouveau. C\u2019est le moment de c\u00e9l\u00e9brer l\u2019h\u00e9ritage de l\u2019AIMS S\u00e9n\u00e9gal et<\/p>","protected":false},"author":16,"featured_media":7832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"categories":[1],"tags":[],"news_types":[32],"acf":[],"author_meta":{"display_name":"lamine","author_link":"https:\/\/aims-senegal.org\/fr\/author\/lamine\/"},"featured_img":"https:\/\/aims-senegal.org\/wp-content\/uploads\/sites\/2\/2026\/05\/Alumni-meet-up.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/aims-senegal.org\/fr\/category\/uncategorized\/\" class=\"advgb-post-tax-term\">Uncategorized<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Uncategorized<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 17 heures il y a","modified":"Mis \u00e0 jour 17 heures il y a"},"absolute_dates":{"created":"Publi\u00e9 le mai 12, 2026","modified":"Mise \u00e0 jour le mai 12, 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le mai 12, 2026 7:09  ","modified":"Mise \u00e0 jour le mai 12, 2026 7:09  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/posts\/7831"}],"collection":[{"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/comments?post=7831"}],"version-history":[{"count":1,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/posts\/7831\/revisions"}],"predecessor-version":[{"id":7833,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/posts\/7831\/revisions\/7833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/media\/7832"}],"wp:attachment":[{"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/media?parent=7831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/categories?post=7831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/tags?post=7831"},{"taxonomy":"news_types","embeddable":true,"href":"https:\/\/aims-senegal.org\/fr\/wp-json\/wp\/v2\/news_types?post=7831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}